{"id":84,"count":4,"description":"","link":"https:\/\/hopelit.de\/en\/lockdown-blog\/","name":"Lockdown Blog","slug":"lockdown-blog","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lockdown Blog Archives - HopeLit<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lockdown Blog Archives - HopeLit\" \/>\n<meta property=\"og:site_name\" content=\"HopeLit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hopelit.de\\\/en\\\/lockdown-blog\\\/\",\"url\":\"https:\\\/\\\/hopelit.de\\\/en\\\/lockdown-blog\\\/\",\"name\":\"Lockdown Blog Archives - HopeLit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hopelit.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hopelit.de\\\/en\\\/lockdown-blog\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hopelit.de\\\/en\\\/lockdown-blog\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"HopeLit\",\"item\":\"https:\\\/\\\/hopelit.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lockdown Blog\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hopelit.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hopelit.de\\\/en\\\/\",\"name\":\"HopeLit\",\"description\":\"Geschichten zum Lernen, Lachen, Hoffen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/hopelit.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hopelit.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hopelit.de\\\/en\\\/#organization\",\"name\":\"HopeLit\",\"url\":\"https:\\\/\\\/hopelit.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hopelit.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hopelit.de\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/hopelit.de\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-2.png\",\"width\":810,\"height\":889,\"caption\":\"HopeLit\"},\"image\":{\"@id\":\"https:\\\/\\\/hopelit.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lockdown Blog Archives - HopeLit","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Lockdown Blog Archives - HopeLit","og_site_name":"HopeLit","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hopelit.de\/en\/lockdown-blog\/","url":"https:\/\/hopelit.de\/en\/lockdown-blog\/","name":"Lockdown Blog Archives - HopeLit","isPartOf":{"@id":"https:\/\/hopelit.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/hopelit.de\/en\/lockdown-blog\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/hopelit.de\/en\/lockdown-blog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"HopeLit","item":"https:\/\/hopelit.de\/en\/"},{"@type":"ListItem","position":2,"name":"Lockdown Blog"}]},{"@type":"WebSite","@id":"https:\/\/hopelit.de\/en\/#website","url":"https:\/\/hopelit.de\/en\/","name":"HopeLit","description":"Geschichten zum Lernen, Lachen, Hoffen.","publisher":{"@id":"https:\/\/hopelit.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hopelit.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hopelit.de\/en\/#organization","name":"HopeLit","url":"https:\/\/hopelit.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hopelit.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hopelit.de\/wp-content\/uploads\/2020\/04\/logo-2.png","contentUrl":"https:\/\/hopelit.de\/wp-content\/uploads\/2020\/04\/logo-2.png","width":810,"height":889,"caption":"HopeLit"},"image":{"@id":"https:\/\/hopelit.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hopelit.de\/en\/wp-json\/wp\/v2\/categories\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hopelit.de\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hopelit.de\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hopelit.de\/en\/wp-json\/wp\/v2\/posts?categories=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}